{"id":1912,"date":"2026-05-22T12:27:06","date_gmt":"2026-05-22T12:27:06","guid":{"rendered":"https:\/\/mymockmate.com\/notes\/?p=1912"},"modified":"2026-05-22T12:27:10","modified_gmt":"2026-05-22T12:27:10","slug":"class-11-maths-exercise-1-4-solutions-sets","status":"publish","type":"post","link":"https:\/\/mymockmate.com\/notes\/class-11-maths-exercise-1-4-solutions-sets\/","title":{"rendered":"Class 11 Maths Exercise 1.4 Solutions \u2013 Sets"},"content":{"rendered":"<div class=\"mymoc-top mymoc-entity-placement\" id=\"mymoc-352002728\"><div id=\"mymoc-2435924462\"><a href=\"https:\/\/amzn.to\/4ehJfM4\" aria-label=\"students acessories\"><img src=\"https:\/\/mymockmate.com\/notes\/wp-content\/uploads\/2026\/06\/students-acessories.png\" alt=\"\" srcset=\"https:\/\/mymockmate.com\/notes\/wp-content\/uploads\/2026\/06\/students-acessories.png 1301w, https:\/\/mymockmate.com\/notes\/wp-content\/uploads\/2026\/06\/students-acessories-300x85.png 300w, https:\/\/mymockmate.com\/notes\/wp-content\/uploads\/2026\/06\/students-acessories-1024x290.png 1024w, https:\/\/mymockmate.com\/notes\/wp-content\/uploads\/2026\/06\/students-acessories-768x218.png 768w\" sizes=\"(max-width: 1301px) 100vw, 1301px\" width=\"1080\" height=\"100\"><\/a><\/div><\/div><div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-bottom-right\"><a href=\"https:\/\/mymockmate.com\/notes\/wp-json\/wp\/v2\/posts\/1912?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/mymockmate.com\/notes\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Print Content\"><span class=\"pdfprnt-button-title pdfprnt-button-print-title\">Print<\/span><\/a> <span class=\"pdfprnt-count-generation\">17<\/span><\/div>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h1 class=\"wp-block-heading\">Short Intro<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">Class 11 Maths Chapter 1 &ldquo;Sets&rdquo; Exercise 1.4 focuses on Union, Intersection, Difference of Sets and Disjoint Sets. In this article, students will get complete NCERT solutions with step-by-step explanations in simple language for better exam preparation. These questions are very important for CBSE Board Exams, School Tests and Competitive Exams.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h1 class=\"wp-block-heading\">Quick Information Box<\/h1>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Particular<\/th><th>Details<\/th><\/tr><\/thead><tbody><tr><td>Class<\/td><td>11<\/td><\/tr><tr><td>Subject<\/td><td>Mathematics<\/td><\/tr><tr><td>Chapter<\/td><td>Sets<\/td><\/tr><tr><td>Exercise<\/td><td>1.4<\/td><\/tr><tr><td>Board<\/td><td>NCERT \/ CBSE<\/td><\/tr><tr><td>Main Topics<\/td><td>Union, Intersection, Difference of Sets<\/td><\/tr><tr><td>Difficulty Level<\/td><td>Easy to Moderate<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h1 class=\"wp-block-heading\">Concepts Used (Topics Covered)<\/h1>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Union of Sets<\/li>\n\n\n\n<li>Intersection of Sets<\/li>\n\n\n\n<li>Difference of Sets<\/li>\n\n\n\n<li>Disjoint Sets<\/li>\n\n\n\n<li>Universal Set<\/li>\n\n\n\n<li>Venn Diagram Concepts<\/li>\n\n\n\n<li>Set Operations<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">According to the NCERT chapter, union means combining elements of both sets, while intersection means common elements.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h1 class=\"wp-block-heading\">Important Formulas<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">Union of Sets<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><math xmlns=\"http:\/\/www.w3.org\/1998\/Math\/MathML\"><semantics><mrow><mi>A<\/mi><mo>&cup;<\/mo><mi>B<\/mi><mo>=<\/mo><mo stretchy=\"false\">{<\/mo><mi>x<\/mi><mo>:<\/mo><mi>x<\/mi><mo>&isin;<\/mo><mi>A<\/mi><mtext>&nbsp;or&nbsp;<\/mtext><mi>x<\/mi><mo>&isin;<\/mo><mi>B<\/mi><mo stretchy=\"false\">}<\/mo><\/mrow><annotation encoding=\"application\/x-tex\">A\\cup B=\\{x:x\\in A\\text{ or }x\\in B\\}<\/annotation><\/semantics><\/math><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Intersection of Sets<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><math xmlns=\"http:\/\/www.w3.org\/1998\/Math\/MathML\"><semantics><mrow><mi>A<\/mi><mo>&cap;<\/mo><mi>B<\/mi><mo>=<\/mo><mo stretchy=\"false\">{<\/mo><mi>x<\/mi><mo>:<\/mo><mi>x<\/mi><mo>&isin;<\/mo><mi>A<\/mi><mtext>&nbsp;and&nbsp;<\/mtext><mi>x<\/mi><mo>&isin;<\/mo><mi>B<\/mi><mo stretchy=\"false\">}<\/mo><\/mrow><annotation encoding=\"application\/x-tex\">A\\cap B=\\{x:x\\in A\\text{ and }x\\in B\\}<\/annotation><\/semantics><\/math><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Difference of Sets<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><math xmlns=\"http:\/\/www.w3.org\/1998\/Math\/MathML\"><semantics><mrow><mi>A<\/mi><mo>&minus;<\/mo><mi>B<\/mi><mo>=<\/mo><mo stretchy=\"false\">{<\/mo><mi>x<\/mi><mo>:<\/mo><mi>x<\/mi><mo>&isin;<\/mo><mi>A<\/mi><mtext>&nbsp;and&nbsp;<\/mtext><mi>x<\/mi><mo mathvariant=\"normal\">&notin;<\/mo><mi>B<\/mi><mo stretchy=\"false\">}<\/mo><\/mrow><annotation encoding=\"application\/x-tex\">A-B=\\{x:x\\in A\\text{ and }x\\notin B\\}<\/annotation><\/semantics><\/math><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Disjoint Sets<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><math xmlns=\"http:\/\/www.w3.org\/1998\/Math\/MathML\"><semantics><mrow><mi>A<\/mi><mo>&cap;<\/mo><mi>B<\/mi><mo>=<\/mo><mi>&#981;<\/mi><\/mrow><annotation encoding=\"application\/x-tex\">A\\cap B=\\phi<\/annotation><\/semantics><\/math><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h1 class=\"wp-block-heading\">Questions &amp; Step-by-step Solutions<\/h1>\n\n\n\n<h1 class=\"wp-block-heading\">Question 1<\/h1>\n\n\n\n<div class=\"internal-linking-related-contents\"><a href=\"https:\/\/mymockmate.com\/notes\/sets-exercise-1-1-solutions-class-11-maths-ncert\/\" class=\"template-2\"><span class=\"cta\">Related Topic to Read more<\/span><span class=\"postTitle\">Sets Exercise 1.1 Solutions Class 11 Maths NCERT<\/span><\/a><\/div><p class=\"wp-block-paragraph\">Find the union of each of the following pairs of sets.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(i)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Given:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">X = {1, 3, 5}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y = {1, 2, 3}<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Solution<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Union means all distinct elements from both sets.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Therefore,<\/p>\n\n\n\n<div class=\"internal-linking-related-contents\"><a href=\"https:\/\/mymockmate.com\/notes\/sets-exercise-1-2-solutions-class-11-maths-ncert\/\" class=\"template-2\"><span class=\"cta\">Related Topic to Read more<\/span><span class=\"postTitle\">Sets Exercise 1.2 Solutions Class 11 Maths NCERT<\/span><\/a><\/div><p class=\"wp-block-paragraph\">X &cup; Y = {1, 2, 3, 5}<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h2 class=\"wp-block-heading\">(ii)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A = {a, e, i, o, u}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B = {a, b, c}<\/p><div class=\"mymoc-middle mymoc-entity-placement\" id=\"mymoc-987929185\"><div id=\"mymoc-3907084244\"><a href=\"https:\/\/amzn.to\/4fDWGbw\" aria-label=\"smartwatch\"><img src=\"https:\/\/mymockmate.com\/notes\/wp-content\/uploads\/2026\/06\/smartwatch.png\" alt=\"\" srcset=\"https:\/\/mymockmate.com\/notes\/wp-content\/uploads\/2026\/06\/smartwatch.png 1717w, https:\/\/mymockmate.com\/notes\/wp-content\/uploads\/2026\/06\/smartwatch-300x71.png 300w, https:\/\/mymockmate.com\/notes\/wp-content\/uploads\/2026\/06\/smartwatch-1024x243.png 1024w, https:\/\/mymockmate.com\/notes\/wp-content\/uploads\/2026\/06\/smartwatch-768x182.png 768w, https:\/\/mymockmate.com\/notes\/wp-content\/uploads\/2026\/06\/smartwatch-1536x364.png 1536w\" sizes=\"(max-width: 1717px) 100vw, 1717px\" width=\"1717\" height=\"407\"><\/a><\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Solution<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A &cup; B = {a, e, i, o, u, b, c}<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h2 class=\"wp-block-heading\">(iii)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A = {Multiples of 3}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B = {Natural numbers less than 6}<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Solution<\/h3>\n\n\n\n<div class=\"internal-linking-related-contents\"><a href=\"https:\/\/mymockmate.com\/notes\/sets-exercise-1-3-solutions-class-11-maths-ncert\/\" class=\"template-2\"><span class=\"cta\">Related Topic to Read more<\/span><span class=\"postTitle\">Sets Exercise 1.3 Solutions Class 11 Maths NCERT<\/span><\/a><\/div><p class=\"wp-block-paragraph\">A = {3, 6, 9, 12, &hellip;}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B = {1, 2, 3, 4, 5}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Therefore,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A &cup; B = {1, 2, 3, 4, 5, 6, 9, 12, &hellip;}<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h2 class=\"wp-block-heading\">(iv)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A = {x : 1 &lt; x &le; 6}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B = {x : 6 &lt; x &lt; 10}<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Solution<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A = {2, 3, 4, 5, 6}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B = {7, 8, 9}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Therefore,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A &cup; B = {2, 3, 4, 5, 6, 7, 8, 9}<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h2 class=\"wp-block-heading\">(v)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A = {1, 2, 3}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B = &phi;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Solution<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Union of any set with null set is the set itself.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Therefore,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A &cup; B = {1, 2, 3}<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h1 class=\"wp-block-heading\">Question 2<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">Let A = {a, b}, B = {a, b, c}. Is A &sub; B ? What is A &cup; B ?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Solution<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Every element of A is present in B.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Therefore,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A &sub; B<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Now,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A &cup; B = {a, b, c}<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h1 class=\"wp-block-heading\">Question 3<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">If A and B are two sets such that A &sub; B, then what is A &cup; B ?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Solution<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">If A is a subset of B, then all elements of A are already present in B.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Therefore,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A &cup; B = B<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h1 class=\"wp-block-heading\">Question 4<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">Given:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A = {1, 2, 3, 4}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B = {3, 4, 5, 6}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C = {5, 6, 7, 8}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D = {7, 8, 9, 10}<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(i) A &cup; B<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">= {1, 2, 3, 4, 5, 6}<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(ii) A &cup; C<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">= {1, 2, 3, 4, 5, 6, 7, 8}<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(iii) B &cup; C<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">= {3, 4, 5, 6, 7, 8}<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(iv) B &cup; D<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">= {3, 4, 5, 6, 7, 8, 9, 10}<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(v) A &cup; B &cup; C<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">= {1, 2, 3, 4, 5, 6, 7, 8}<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(vi) A &cup; B &cup; D<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">= {1, 2, 3, 4, 5, 6, 7, 8, 9, 10}<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(vii) B &cup; C &cup; D<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">= {3, 4, 5, 6, 7, 8, 9, 10}<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h1 class=\"wp-block-heading\">Question 5<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">Find the intersection of each pair of sets of Question 1.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(i)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">X &cap; Y = {1, 3}<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(ii)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A &cap; B = {a}<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(iii)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A &cap; B = {3}<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(iv)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A &cap; B = &phi;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(v)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A &cap; &phi; = &phi;<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h1 class=\"wp-block-heading\">Question 6<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">Given:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A = {3, 5, 7, 9, 11}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B = {7, 9, 11, 13}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C = {11, 13, 15}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D = {15, 17}<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(i) A &cap; B<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">= {7, 9, 11}<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(ii) B &cap; C<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">= {11, 13}<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(iii) A &cap; C &cap; D<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">= &phi;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(iv) A &cap; C<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">= {11}<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(v) B &cap; D<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">= &phi;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(vi) A &cap; (B &cup; C)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">B &cup; C = {7, 9, 11, 13, 15}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Therefore,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A &cap; (B &cup; C) = {7, 9, 11}<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(vii) A &cap; D<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">= &phi;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(viii) A &cap; (B &cup; D)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">B &cup; D = {7, 9, 11, 13, 15, 17}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Therefore,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A &cap; (B &cup; D) = {7, 9, 11}<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(ix)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">(A &cap; B) &cap; (B &cup; C)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">= {7, 9, 11}<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(x)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">(A &cup; D) &cap; (B &cup; C)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A &cup; D = {3, 5, 7, 9, 11, 15, 17}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B &cup; C = {7, 9, 11, 13, 15}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Therefore,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">= {7, 9, 11, 15}<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h1 class=\"wp-block-heading\">Question 7<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">A = Natural Numbers<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B = Even Natural Numbers<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C = Odd Natural Numbers<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D = Prime Numbers<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Answers<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">(i) A &cap; B = Even Natural Numbers<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(ii) A &cap; C = Odd Natural Numbers<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(iii) A &cap; D = Prime Numbers<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(iv) B &cap; C = &phi;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(v) B &cap; D = {2}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(vi) C &cap; D = {3, 5, 7, 11, &hellip;}<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h1 class=\"wp-block-heading\">Question 8<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">Which pairs are disjoint sets?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(i)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Common element = 4<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Not disjoint<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(ii)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Common element = e<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Not disjoint<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(iii)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Even integers and odd integers have no common element.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Therefore,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">They are disjoint sets.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h1 class=\"wp-block-heading\">Question 9<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">Given:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A = {3, 6, 9, 12, 15, 18, 21}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B = {4, 8, 12, 16, 20}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C = {2, 4, 6, 8, 10, 12, 14, 16}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D = {5, 10, 15, 20}<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Answers<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">(i) A &ndash; B = {3, 6, 9, 15, 18, 21}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(ii) A &ndash; C = {3, 9, 15, 18, 21}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(iii) A &ndash; D = {3, 6, 9, 12, 18, 21}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(iv) B &ndash; A = {4, 8, 16, 20}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(v) C &ndash; A = {2, 4, 8, 10, 14, 16}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(vi) D &ndash; A = {5, 10, 20}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(vii) B &ndash; C = {20}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(viii) B &ndash; D = {4, 8, 12, 16}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(ix) C &ndash; B = {2, 6, 10, 14}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(x) D &ndash; B = {5, 10, 15}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(xi) C &ndash; D = {2, 4, 6, 8, 12, 14, 16}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(xii) D &ndash; C = {5, 10, 15, 20}<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h1 class=\"wp-block-heading\">Question 10<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">X = {a, b, c, d}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y = {f, b, d, g}<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(i)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">X &ndash; Y = {a, c}<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(ii)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Y &ndash; X = {f, g}<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(iii)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">X &cap; Y = {b, d}<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h1 class=\"wp-block-heading\">Question 11<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">If R is set of real numbers and Q is set of rational numbers, then:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R &ndash; Q = Irrational Numbers<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h1 class=\"wp-block-heading\">Question 12<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">State True or False.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(i)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">False<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Because 3 is common.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(ii)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">False<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Because a is common.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(iii)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">True<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No common element.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">(iv)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">True<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No common element.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h1 class=\"wp-block-heading\">Common Mistakes<\/h1>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Repeating elements while writing union.<\/li>\n\n\n\n<li>Forgetting common elements in intersection.<\/li>\n\n\n\n<li>Confusing A &ndash; B with B &ndash; A.<\/li>\n\n\n\n<li>Writing repeated elements in sets.<\/li>\n\n\n\n<li>Forgetting that &phi; union A = A.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h1 class=\"wp-block-heading\">Exam Tips<\/h1>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Always write distinct elements only once.<\/li>\n\n\n\n<li>Use curly brackets properly.<\/li>\n\n\n\n<li>Learn formulas of union and intersection.<\/li>\n\n\n\n<li>Solve questions using Venn diagrams for better understanding.<\/li>\n\n\n\n<li>Practice difference of sets carefully.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h1 class=\"wp-block-heading\">Practice MCQs<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">1. If A = {1,2,3} and B = {3,4,5}, then A &cap; B is:<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A) {1,2}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B) {3}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C) {4,5}<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D) &phi;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Answer:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">B) {3}<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h2 class=\"wp-block-heading\">2. If A &sub; B, then A &cup; B equals:<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A) A<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B) &phi;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C) B<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D) None<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Answer:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">C) B<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h2 class=\"wp-block-heading\">3. Two sets are disjoint if:<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A) They are equal<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B) They have common elements<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C) Their intersection is &phi;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D) Their union is &phi;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Answer:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">C) Their intersection is &phi;<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h1 class=\"wp-block-heading\">FAQ Section<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">Q1. What is union of sets?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Union means combining all elements of both sets without repetition.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h2 class=\"wp-block-heading\">Q2. What is intersection of sets?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Intersection means common elements between two sets.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h2 class=\"wp-block-heading\">Q3. What are disjoint sets?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Sets having no common element are called disjoint sets.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h2 class=\"wp-block-heading\">Q4. What is null set?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A set having no element is called null set or empty set.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#128216; Prepare Smarter with MyMockMate!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#9989; Chapter-wise NCERT Solutions<br>&#9989; Important Notes &amp; MCQs<br>&#9989; Online Mock Tests<br>&#9989; Instant Result &amp; Analysis<br>&#9989; CBSE Board Preparation<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Start learning now on <a target=\"_blank\" rel=\"noreferrer noopener\" href=\"https:\/\/www.mymockmate.com?utm_source=chatgpt.com\">MyMockMate<\/a><\/p>\n<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-bottom-right\"><a href=\"https:\/\/mymockmate.com\/notes\/wp-json\/wp\/v2\/posts\/1912?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/mymockmate.com\/notes\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Print Content\"><span class=\"pdfprnt-button-title pdfprnt-button-print-title\">Print<\/span><\/a> <span class=\"pdfprnt-count-generation\">17<\/span><\/div><div class=\"mymoc-bottom mymoc-entity-placement\" id=\"mymoc-4152680332\"><div id=\"mymoc-3530312457\"><a href=\"https:\/\/amzn.to\/4v5gV6P\" aria-label=\"calculators\"><img src=\"https:\/\/mymockmate.com\/notes\/wp-content\/uploads\/2026\/06\/calculators.png\" alt=\"\" srcset=\"https:\/\/mymockmate.com\/notes\/wp-content\/uploads\/2026\/06\/calculators.png 1302w, https:\/\/mymockmate.com\/notes\/wp-content\/uploads\/2026\/06\/calculators-300x99.png 300w, https:\/\/mymockmate.com\/notes\/wp-content\/uploads\/2026\/06\/calculators-1024x338.png 1024w, https:\/\/mymockmate.com\/notes\/wp-content\/uploads\/2026\/06\/calculators-768x254.png 768w\" sizes=\"(max-width: 1302px) 100vw, 1302px\" width=\"1302\" height=\"430\"><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p> 17 Short Intro Class 11 Maths Chapter 1 &ldquo;Sets&rdquo; Exercise 1.4 focuses on Union, Intersection, Difference of Sets and Disjoint Sets. In this article,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1913,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"postBodyCss":"","postBodyMargin":[],"postBodyPadding":[],"postBodyBackground":{"backgroundType":"classic","gradient":""},"footnotes":""},"categories":[6,9],"tags":[187,286,285,301,335,329,298,332,328,327,326,304,297,306,62,308,159,47,330,334,300,305,309,287,303,331,296,299,333],"class_list":["post-1912","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-class-11","category-maths-class-11","tag-cbse-board-maths-preparation","tag-cbse-class-11-maths","tag-class-11-maths","tag-class-11-maths-notes","tag-class-11-sets-solutions","tag-complement-of-sets","tag-difference-of-sets","tag-difference-of-sets-questions","tag-disjoint-sets","tag-exercise-1-4-ncert-solutions","tag-exercise-1-4-solutions","tag-important-questions-sets","tag-intersection-of-sets","tag-mathematical-sets","tag-maths-chapter-1-solutions","tag-mymockmate","tag-ncert-maths-notes","tag-ncert-solutions","tag-properties-of-sets","tag-set-identities","tag-set-operations","tag-set-theory-basics","tag-sets","tag-sets-chapter-1","tag-sets-mcqs","tag-union-and-intersection","tag-union-of-sets","tag-venn-diagram","tag-venn-diagram-questions"],"featured_image_src":"https:\/\/mymockmate.com\/notes\/wp-content\/uploads\/2026\/05\/Class-11-Maths-Exercise-1.4-Solutions-\u2013-Sets.png","author_info":{"display_name":"Team Mymockmate","author_link":"https:\/\/mymockmate.com\/notes\/author\/bsm_adm\/"},"_links":{"self":[{"href":"https:\/\/mymockmate.com\/notes\/wp-json\/wp\/v2\/posts\/1912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mymockmate.com\/notes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mymockmate.com\/notes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mymockmate.com\/notes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mymockmate.com\/notes\/wp-json\/wp\/v2\/comments?post=1912"}],"version-history":[{"count":1,"href":"https:\/\/mymockmate.com\/notes\/wp-json\/wp\/v2\/posts\/1912\/revisions"}],"predecessor-version":[{"id":1914,"href":"https:\/\/mymockmate.com\/notes\/wp-json\/wp\/v2\/posts\/1912\/revisions\/1914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mymockmate.com\/notes\/wp-json\/wp\/v2\/media\/1913"}],"wp:attachment":[{"href":"https:\/\/mymockmate.com\/notes\/wp-json\/wp\/v2\/media?parent=1912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mymockmate.com\/notes\/wp-json\/wp\/v2\/categories?post=1912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mymockmate.com\/notes\/wp-json\/wp\/v2\/tags?post=1912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}