{"id":1519,"count":1,"description":"","link":"https:\/\/mymockmate.com\/notes\/tag\/theatre-equipment\/","name":"Theatre Equipment","slug":"theatre-equipment","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/mymockmate.com\/notes\/wp-json\/wp\/v2\/tags\/1519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mymockmate.com\/notes\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/mymockmate.com\/notes\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/mymockmate.com\/notes\/wp-json\/wp\/v2\/posts?tags=1519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}